{"id":17966,"date":"2024-09-08T17:49:16","date_gmt":"2024-09-08T15:49:16","guid":{"rendered":"https:\/\/westjysk-coins.com\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/"},"modified":"2024-09-08T17:49:16","modified_gmt":"2024-09-08T15:49:16","slug":"50-krone-1958-a2-sunesen-riim-kva-0-01","status":"publish","type":"product","link":"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/","title":{"rendered":"50 krone 1958 A2 Sunesen\/Riim Kva. 0-01"},"content":{"rendered":"<p>Sieg 134 DOP 143 Pick 45<\/p>\n<p>Svag midterfold<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sieg 134 DOP 143 Pick 45 Svag midterfold<\/p>\n","protected":false},"featured_media":17892,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[411,352,374,375],"product_tag":[],"class_list":{"0":"post-17966","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-50-crowns","7":"product_cat-all-products","8":"product_cat-banknotes","9":"product_cat-denmark-en","10":"sales-flash-overlay","11":"woocommerce-text-align-center","12":"woocommerce-image-align-center","13":"do-quantity-buttons","15":"first","16":"instock","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>50 krone 1958 A2 Sunesen\/Riim Kva. 0-01 | Westjysk Coins<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"50 krone 1958 A2 Sunesen\/Riim Kva. 0-01 | Westjysk Coins\" \/>\n<meta property=\"og:description\" content=\"Sieg 134 DOP 143 Pick 45 Svag midterfold\" \/>\n<meta property=\"og:url\" content=\"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Westjysk Coins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/\",\"url\":\"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/\",\"name\":\"50 krone 1958 A2 Sunesen\/Riim Kva. 0-01 | Westjysk Coins\",\"isPartOf\":{\"@id\":\"https:\/\/westjysk-coins.webserver1.dk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/westjysk-coins.com\/wp-content\/uploads\/2024\/09\/Photoroom_038_20240908_144514.jpeg\",\"datePublished\":\"2024-09-08T15:49:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/#primaryimage\",\"url\":\"https:\/\/westjysk-coins.com\/wp-content\/uploads\/2024\/09\/Photoroom_038_20240908_144514.jpeg\",\"contentUrl\":\"https:\/\/westjysk-coins.com\/wp-content\/uploads\/2024\/09\/Photoroom_038_20240908_144514.jpeg\",\"width\":2016,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Forside\",\"item\":\"https:\/\/westjysk-coins.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/westjysk-coins.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"50 krone 1958 A2 Sunesen\/Riim Kva. 0-01\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/westjysk-coins.webserver1.dk\/#website\",\"url\":\"https:\/\/westjysk-coins.webserver1.dk\/\",\"name\":\"Westjysk Coins\",\"description\":\"K\u00f8b, salg og vurderinger af gamle m\u00f8nter, sedler, guld og s\u00f8lv, b\u00e5de danske og udlandske\",\"publisher\":{\"@id\":\"https:\/\/westjysk-coins.webserver1.dk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/westjysk-coins.webserver1.dk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/westjysk-coins.webserver1.dk\/#organization\",\"name\":\"Westjysk Coins\",\"url\":\"https:\/\/westjysk-coins.webserver1.dk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/westjysk-coins.webserver1.dk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/westjysk-coins.com\/wp-content\/uploads\/2024\/01\/westjysk-logo.svg\",\"contentUrl\":\"https:\/\/westjysk-coins.com\/wp-content\/uploads\/2024\/01\/westjysk-logo.svg\",\"width\":312,\"height\":44,\"caption\":\"Westjysk Coins\"},\"image\":{\"@id\":\"https:\/\/westjysk-coins.webserver1.dk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"50 krone 1958 A2 Sunesen\/Riim Kva. 0-01 | Westjysk Coins","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/","og_locale":"en_US","og_type":"article","og_title":"50 krone 1958 A2 Sunesen\/Riim Kva. 0-01 | Westjysk Coins","og_description":"Sieg 134 DOP 143 Pick 45 Svag midterfold","og_url":"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/","og_site_name":"Westjysk Coins","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/","url":"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/","name":"50 krone 1958 A2 Sunesen\/Riim Kva. 0-01 | Westjysk Coins","isPartOf":{"@id":"https:\/\/westjysk-coins.webserver1.dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/#primaryimage"},"image":{"@id":"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/#primaryimage"},"thumbnailUrl":"https:\/\/westjysk-coins.com\/wp-content\/uploads\/2024\/09\/Photoroom_038_20240908_144514.jpeg","datePublished":"2024-09-08T15:49:16+00:00","breadcrumb":{"@id":"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/#primaryimage","url":"https:\/\/westjysk-coins.com\/wp-content\/uploads\/2024\/09\/Photoroom_038_20240908_144514.jpeg","contentUrl":"https:\/\/westjysk-coins.com\/wp-content\/uploads\/2024\/09\/Photoroom_038_20240908_144514.jpeg","width":2016,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/westjysk-coins.com\/en\/product\/50-krone-1958-a2-sunesen-riim-kva-0-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Forside","item":"https:\/\/westjysk-coins.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/westjysk-coins.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"50 krone 1958 A2 Sunesen\/Riim Kva. 0-01"}]},{"@type":"WebSite","@id":"https:\/\/westjysk-coins.webserver1.dk\/#website","url":"https:\/\/westjysk-coins.webserver1.dk\/","name":"Westjysk Coins","description":"K\u00f8b, salg og vurderinger af gamle m\u00f8nter, sedler, guld og s\u00f8lv, b\u00e5de danske og udlandske","publisher":{"@id":"https:\/\/westjysk-coins.webserver1.dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/westjysk-coins.webserver1.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/westjysk-coins.webserver1.dk\/#organization","name":"Westjysk Coins","url":"https:\/\/westjysk-coins.webserver1.dk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/westjysk-coins.webserver1.dk\/#\/schema\/logo\/image\/","url":"https:\/\/westjysk-coins.com\/wp-content\/uploads\/2024\/01\/westjysk-logo.svg","contentUrl":"https:\/\/westjysk-coins.com\/wp-content\/uploads\/2024\/01\/westjysk-logo.svg","width":312,"height":44,"caption":"Westjysk Coins"},"image":{"@id":"https:\/\/westjysk-coins.webserver1.dk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/westjysk-coins.com\/en\/wp-json\/wp\/v2\/product\/17966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/westjysk-coins.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/westjysk-coins.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/westjysk-coins.com\/en\/wp-json\/wp\/v2\/comments?post=17966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/westjysk-coins.com\/en\/wp-json\/wp\/v2\/media\/17892"}],"wp:attachment":[{"href":"https:\/\/westjysk-coins.com\/en\/wp-json\/wp\/v2\/media?parent=17966"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/westjysk-coins.com\/en\/wp-json\/wp\/v2\/product_brand?post=17966"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/westjysk-coins.com\/en\/wp-json\/wp\/v2\/product_cat?post=17966"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/westjysk-coins.com\/en\/wp-json\/wp\/v2\/product_tag?post=17966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}